{"id":660,"date":"2017-01-27T23:34:10","date_gmt":"2017-01-27T22:34:10","guid":{"rendered":"http:\/\/constructionguysebas.bravad-dev.com\/realisations\/industrielles\/les-entreprises-j-baillargeon-inc\/"},"modified":"2017-05-15T16:17:32","modified_gmt":"2017-05-15T15:17:32","slug":"les-entreprises-j-baillargeon-inc","status":"publish","type":"page","link":"https:\/\/guysebas.com\/en\/realisations\/industrials\/les-entreprises-j-baillargeon-inc\/","title":{"rendered":"Les Entreprises J. Baillargeon Inc."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":656,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/realisation-complete.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-660","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Entreprises J. Baillargeon Inc. - Construction Guy Sebas<\/title>\n<meta name=\"description\" content=\"Constructions Guy S\u00e9bas carried out this extension of a garage section for Les Entreprises J. Baillargeon Inc. in Sherbrooke, as a private contract.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guysebas.com\/en\/realisations\/industrials\/les-entreprises-j-baillargeon-inc\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Entreprises J. Baillargeon Inc. - Construction Guy Sebas\" \/>\n<meta property=\"og:description\" content=\"Constructions Guy S\u00e9bas carried out this extension of a garage section for Les Entreprises J. Baillargeon Inc. in Sherbrooke, as a private contract.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guysebas.com\/en\/realisations\/industrials\/les-entreprises-j-baillargeon-inc\/\" \/>\n<meta property=\"og:site_name\" content=\"Construction Guy Sebas\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-15T15:17:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/constructionguysebas.bravad-dev.com\/wp-content\/uploads\/2017\/01\/facebook-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/guysebas.com\\\/en\\\/realisations\\\/industrials\\\/les-entreprises-j-baillargeon-inc\\\/\",\"url\":\"https:\\\/\\\/guysebas.com\\\/en\\\/realisations\\\/industrials\\\/les-entreprises-j-baillargeon-inc\\\/\",\"name\":\"Les Entreprises J. Baillargeon Inc. - Construction Guy Sebas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/guysebas.com\\\/en\\\/#website\"},\"datePublished\":\"2017-01-27T22:34:10+00:00\",\"dateModified\":\"2017-05-15T15:17:32+00:00\",\"description\":\"Constructions Guy S\u00e9bas carried out this extension of a garage section for Les Entreprises J. Baillargeon Inc. in Sherbrooke, as a private contract.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/guysebas.com\\\/en\\\/realisations\\\/industrials\\\/les-entreprises-j-baillargeon-inc\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/guysebas.com\\\/en\\\/realisations\\\/industrials\\\/les-entreprises-j-baillargeon-inc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/guysebas.com\\\/en\\\/realisations\\\/industrials\\\/les-entreprises-j-baillargeon-inc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/guysebas.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9alisations\",\"item\":\"https:\\\/\\\/guysebas.com\\\/en\\\/realisations\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"industrials\",\"item\":\"https:\\\/\\\/guysebas.com\\\/en\\\/realisations\\\/industrielles\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Les Entreprises J. Baillargeon Inc.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/guysebas.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/guysebas.com\\\/en\\\/\",\"name\":\"Construction Guy Sebas\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/guysebas.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Entreprises J. Baillargeon Inc. - Construction Guy Sebas","description":"Constructions Guy S\u00e9bas carried out this extension of a garage section for Les Entreprises J. Baillargeon Inc. in Sherbrooke, as a private contract.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guysebas.com\/en\/realisations\/industrials\/les-entreprises-j-baillargeon-inc\/","og_locale":"en_US","og_type":"article","og_title":"Les Entreprises J. Baillargeon Inc. - Construction Guy Sebas","og_description":"Constructions Guy S\u00e9bas carried out this extension of a garage section for Les Entreprises J. Baillargeon Inc. in Sherbrooke, as a private contract.","og_url":"https:\/\/guysebas.com\/en\/realisations\/industrials\/les-entreprises-j-baillargeon-inc\/","og_site_name":"Construction Guy Sebas","article_modified_time":"2017-05-15T15:17:32+00:00","og_image":[{"url":"http:\/\/constructionguysebas.bravad-dev.com\/wp-content\/uploads\/2017\/01\/facebook-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/guysebas.com\/en\/realisations\/industrials\/les-entreprises-j-baillargeon-inc\/","url":"https:\/\/guysebas.com\/en\/realisations\/industrials\/les-entreprises-j-baillargeon-inc\/","name":"Les Entreprises J. Baillargeon Inc. - Construction Guy Sebas","isPartOf":{"@id":"https:\/\/guysebas.com\/en\/#website"},"datePublished":"2017-01-27T22:34:10+00:00","dateModified":"2017-05-15T15:17:32+00:00","description":"Constructions Guy S\u00e9bas carried out this extension of a garage section for Les Entreprises J. Baillargeon Inc. in Sherbrooke, as a private contract.","breadcrumb":{"@id":"https:\/\/guysebas.com\/en\/realisations\/industrials\/les-entreprises-j-baillargeon-inc\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/guysebas.com\/en\/realisations\/industrials\/les-entreprises-j-baillargeon-inc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/guysebas.com\/en\/realisations\/industrials\/les-entreprises-j-baillargeon-inc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/guysebas.com\/en\/"},{"@type":"ListItem","position":2,"name":"R\u00e9alisations","item":"https:\/\/guysebas.com\/en\/realisations\/"},{"@type":"ListItem","position":3,"name":"industrials","item":"https:\/\/guysebas.com\/en\/realisations\/industrielles\/"},{"@type":"ListItem","position":4,"name":"Les Entreprises J. Baillargeon Inc."}]},{"@type":"WebSite","@id":"https:\/\/guysebas.com\/en\/#website","url":"https:\/\/guysebas.com\/en\/","name":"Construction Guy Sebas","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guysebas.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/guysebas.com\/en\/wp-json\/wp\/v2\/pages\/660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guysebas.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/guysebas.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/guysebas.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guysebas.com\/en\/wp-json\/wp\/v2\/comments?post=660"}],"version-history":[{"count":0,"href":"https:\/\/guysebas.com\/en\/wp-json\/wp\/v2\/pages\/660\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/guysebas.com\/en\/wp-json\/wp\/v2\/pages\/656"}],"wp:attachment":[{"href":"https:\/\/guysebas.com\/en\/wp-json\/wp\/v2\/media?parent=660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}